{"id":16290,"date":"2010-02-08T03:33:00","date_gmt":"2010-02-08T02:33:00","guid":{"rendered":"http:\/\/redatea.net\/?guid=08705c7bd7130d85415913a54d1983c6"},"modified":"2010-02-08T03:55:57","modified_gmt":"2010-02-08T02:55:57","slug":"la-virgen-de-guadalupe-al-descubierto-2","status":"publish","type":"post","link":"http:\/\/feedproxy.google.com\/~r\/ReligionesAlDescubierto\/~3\/fXvQC-BHi_A\/la-virgen-de-guadalupe-al-descubierto.html","title":{"rendered":"LA VIRGEN DE GUADALUPE AL DESCUBIERTO"},"content":{"rendered":"<a onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\" href=\"http:\/\/3.bp.blogspot.com\/_Hox9a4QhzdM\/S299DboUmcI\/AAAAAAAAAI8\/GX7d8bHPUJQ\/s1600-h\/virgen_de_guadalupe_y_juan_diego_1.jpg\"><img style=\"display: block; margin: 0px auto 10px; text-align: center; cursor: pointer; width: 320px; height: 254px;\" src=\"http:\/\/3.bp.blogspot.com\/_Hox9a4QhzdM\/S299DboUmcI\/AAAAAAAAAI8\/GX7d8bHPUJQ\/s320\/virgen_de_guadalupe_y_juan_diego_1.jpg\" alt=\"\" id=\"BLOGGER_PHOTO_ID_5435700773169437122\" border=\"0\" \/><\/a><span style=\"font-weight: bold;\">Por guerreropirata<\/span><br \/><br \/>Vamos primero a recordar como sucedio este acontecimiento \"milagroso\":<br \/><br \/>Seg\u00c3\u00ban la historia la Virgen Mar\u00c3\u00ada se manifest\u00c3\u00b3 al ind\u00c3\u00adgena <span style=\"font-weight: bold;\">Juan  Diego<\/span>, quien era originario de Cuautitl\u00c3\u00a1n, <span style=\"font-weight: bold;\">y a su t\u00c3\u00ado Juan Bernardino,  ambos convertidos al cristianismo pocos a\u00c3\u00b1os atr\u00c3\u00a1s a ra\u00c3\u00adz de la  conquista espa\u00c3\u00b1ola.<\/span> <p>El <span style=\"font-weight: bold;\">Nican Mopohua<\/span>, donde se refleja esta historia, dice que la Virgen  le revel\u00c3\u00b3 el nombre \u00c2\u00abGuadalupe\u00c2\u00bb a Bernardino cuando \u00c3\u00a9ste se encontraba  enfermo de gravedad, aunque los entendidos en el tema afirman que es  imposible que la Virgen se nombrara a s\u00c3\u00ad misma Guadalupe, ya que Juan  Bernardino no entend\u00c3\u00ada la lengua castellana tra\u00c3\u00adda por los espa\u00c3\u00b1oles al  Nuevo Mundo.<\/p> <p>Se dice que esta aparici\u00c3\u00b3n de la virgen, en su advocaci\u00c3\u00b3n de Virgen  de Guadalupe, se present\u00c3\u00b3 en varias ocasiones ante <span style=\"font-weight: bold;\">Juan Diego el s\u00c3\u00a1bado 9  de diciembre de 1531 en el cerro del Tepeyac<\/span> y le pidi\u00c3\u00b3 que fuera en  busca del obispo y le dijera que ella solicitaba la creaci\u00c3\u00b3n de un  templo en ese lugar. Cuenta la historia que el ind\u00c3\u00adgena fue en busca de <span style=\"font-weight: bold;\">Fray Juan de Zum\u00c3\u00a1rraga <\/span>para contarle la solicitud de la virgen, siendo  que Fray Juan no crey\u00c3\u00b3 en las apariciones. <span style=\"font-weight: bold;\">As\u00c3\u00ad fue c\u00c3\u00b3mo el fraile le  pidi\u00c3\u00b3 una prueba de las apariciones de la Virgen.<\/span><\/p> <p>En respuesta a la petici\u00c3\u00b3n del obispo, la aparici\u00c3\u00b3n mariana le pidi\u00c3\u00b3  al ind\u00c3\u00adgena que <span style=\"font-weight: bold;\">cortara unas rosas de Castilla de la cumbre del cerro  Tepeyac<\/span> y se las llevara al obispo El ind\u00c3\u00adgena guard\u00c3\u00b3 las rosas dentro  de su manto o ayate (tipo de toga abierta por los lados). Al llegar a  donde estaba el obispo, \u00c3\u00a9ste estir\u00c3\u00b3 su ayate para tender las rosas sobre  la mesa, con la sorpresa de que la imagen estilizada de la Virgen de  Guadalupe se encontraba grabada en el manto. <span style=\"font-weight: bold;\">La prueba para el fraile no  fueron solamente las rosas, sino el milagro de la pintura de la Virgen  de Guadalupe sobre el ayate.<\/span><\/p><p>Pero en el libro que se llama <span style=\"font-weight: bold;\">\u00e2\u20ac\u0153Cartas  acerca del origen de la imagen de nuestra se\u00c3\u00b1ora de Guadalupe\u00e2\u20ac\u009d<\/span>, de  M\u00c3\u00a9xico, que fue escrita por<span style=\"font-weight: bold;\"> Don Joaqu\u00c3\u00adn Garc\u00c3\u00ada Icazbalceta<\/span>, quien es un  historiador mexicano <span style=\"font-weight: bold;\">cuyo estudio corresponde a 1883<\/span>, y quien fue  mandado a hacer dicha investigaci\u00c3\u00b3n por una orden, <span style=\"font-weight: bold;\">pone en duda la verdad del mito de las apariciones de la  Virgen de Guadalupe.<\/span><br \/><br \/>En el libro y en el relato se dice que el testigo principal  de las apariciones es <span style=\"font-weight: bold;\">Fray Juan de Zum\u00c3\u00a1rraga<\/span>, pero se ha encontrado tambi\u00c3\u00a9n que  en todos los escritos de este fraile en ning\u00c3\u00ban lugar ha dejado rastro,  ni siquiera menciona la palabra Guadalupe. <span style=\"font-weight: bold;\">De hecho \u00c3\u00a9l mismo niega la  existencia de milagros<\/span>, afirmando que \u00c3\u00a9l nunca fue testigo en su tiempo  de milagros de los que se daban en tiempos de la Biblia.<br \/><br \/>Otra de  las cuestiones que se plantean es que el ind\u00c3\u00adgena <span style=\"font-weight: bold;\">Juan Diego<\/span>, cuando  supuestamente se le apareci\u00c3\u00b3 la Virgen, iba de Cuautitl\u00c3\u00a1n hacia el  templo de Tlaltilolco, <span style=\"font-weight: bold;\">pero en 1531 no exist\u00c3\u00ada ning\u00c3\u00ban templo en  Tlaltilolco, es una realidad<\/span>.<br \/><span style=\"font-weight: bold;\"><\/span><\/p><p>Otra cuesti\u00c3\u00b3n es que dice la leyenda que el t\u00c3\u00ado de Juan Diego,  <span style=\"font-weight: bold;\">Bernardino<\/span>, iba a recibir la extrema unci\u00c3\u00b3n, ya que \u00c3\u00a9l estaba  agonizando, <span style=\"font-weight: bold;\">pero en 1531 a los ind\u00c3\u00adgenas no se les daba ese tipo de  tratamiento<\/span>, lo cual esta comprobado hist\u00c3\u00b3ricamente, <span style=\"font-weight: bold;\">ya que para esa  \u00c3\u00a9poca todav\u00c3\u00ada mucha gente los consideraban como animales<\/span>, que no ten\u00c3\u00adan  alma, y si acaso se les bautizaba.<br \/><br \/>Al ver los escritos de  <span style=\"font-weight: bold;\">Don Joaqu\u00c3\u00adn Garc\u00c3\u00ada Icazbalceta<\/span> uno se da cuenta que no hay absolutamente  ninguna apalabra, no hay ning\u00c3\u00ban documentos hist\u00c3\u00b3rico,<span style=\"font-weight: bold;\"> no hay nada que  hable hist\u00c3\u00b3ricamente de las apariciones de la Virgen de Guadalupe<\/span> en esa  \u00c3\u00a9poca, cuando fue un evento sumamente importante, <span style=\"font-weight: bold;\">pero nada lo menciona  sino hasta el a\u00c3\u00b1o 1648,<\/span> es decir, m\u00c3\u00a1s de cien a\u00c3\u00b1os despu\u00c3\u00a9s de  supuestamente sucedido el milagro.<br \/><\/p><p>Hay que tener en cuenta que curiosamente en  el <span style=\"font-weight: bold;\">cerro del Tepeyac antes se adoraba Tonatiu, la madre de los Dioses, y  los espa\u00c3\u00b1oles hicieron algo muy inteligente: Quetzalc\u00c3\u00b3atl pas\u00c3\u00b3 a ser  Jesucristo, Tlaloc pas\u00c3\u00b3 a ser San Juan Bautista, y Tonatiu, la  mujercita, paso a ser la Virgen de Guadalupe, la madre de Dios,<\/span><\/p><p>Lo que suced\u00c3\u00ada en esa \u00c3\u00a9poca era que al  parecer todo el dinero de los pobladores se iba para las iglesias de  provincia, y <span style=\"font-weight: bold;\">la iglesia de la capital necesitaba generar recursos<\/span>, y  para eso necesitaba crear algo dram\u00c3\u00a1tico, algo impactante, <span style=\"font-weight: bold;\">algo como la  aparici\u00c3\u00b3n de alguna virgen en alg\u00c3\u00ban lugar de la capital.<\/span><br \/><\/p><p><span style=\"font-weight: bold;\">Pienso que las apariciones de la Virgen de Guadalupe fue una gran mentira, fue inventada para someter a  la cultura ind\u00c3\u00adgena,<\/span> ya que en esos momentos de la historia los indigenas estaban revelandose contra los espa\u00c3\u00b1oles y estos necesitaban <span style=\"font-weight: bold;\">\"algo divino\"<\/span> para que sus intereses no se vean mermados y sigan sometiendo a los indigenas de Mexico asi como lo hicieron con toda America.<br \/><br \/><br \/><\/p><div class=\"blogger-post-footer\"><img width='1' height='1' src='https:\/\/blogger.googleusercontent.com\/tracker\/4972893445575834141-6212928782341269914?l=jehovadesenmascarado.blogspot.com' alt='' \/><\/div><img src=\"http:\/\/feeds.feedburner.com\/~r\/ReligionesAlDescubierto\/~4\/fXvQC-BHi_A\" height=\"1\" width=\"1\"\/>","protected":false},"excerpt":{"rendered":"<p>Por guerreropirataVamos primero a recordar como sucedio este acontecimiento &#8220;milagroso&#8221;:Seg\u00c3\u00ban la historia la Virgen Mar\u00c3\u00ada se manifest\u00c3\u00b3 al ind\u00c3\u00adgena Juan  Diego, quien era originario de Cuautitl\u00c3\u00a1n, y a su t\u00c3\u00ado Juan Bernardino,  ambos convertidos al &#8230;<\/p>\n","protected":false},"author":172,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[148,4,213,149,212],"tags":[],"class_list":["post-16290","post","type-post","status-publish","format-standard","hentry","category-apariciones","category-blogs-colaboradores","category-juan-diego","category-virgen","category-virgen-de-guadalupe"],"_links":{"self":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts\/16290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/users\/172"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/comments?post=16290"}],"version-history":[{"count":0,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts\/16290\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/media?parent=16290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/categories?post=16290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/tags?post=16290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}