{"id":20418,"date":"2013-02-15T13:06:00","date_gmt":"2013-02-15T12:06:00","guid":{"rendered":"http:\/\/redatea.net\/?guid=1a886f72bba1013ae1cc20522bb9cf82"},"modified":"2013-02-15T19:44:24","modified_gmt":"2013-02-15T18:44:24","slug":"el-poligrafo-absoluto","status":"publish","type":"post","link":"http:\/\/abordodelottoneurath.blogspot.com\/2013\/02\/el-poligrafo-absoluto.html","title":{"rendered":"El pol\u00c3\u00adgrafo absoluto"},"content":{"rendered":"<span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\">(Contin\u00c3\u00baa la conversaci\u00c3\u00b3n en <a href=\"http:\/\/opusprima.com\/2013\/02\/11\/es-posible-una-sociedad-cristiana-el-cristiano-no-es-perfecto-pero-el-cristianismo-si\/#comment-15866\" >Opus Prima<\/a>).<\/span><\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\"><br \/><\/span><\/span><br \/><div class=\"separator\" style=\"clear: both; text-align: center;\"><a href=\"http:\/\/2.bp.blogspot.com\/-qScJR8EKJjs\/UR4jHUJkiKI\/AAAAAAAAE3Y\/2xHYByzRZos\/s1600\/polygraph2.jpeg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img border=\"0\" height=\"282\" src=\"http:\/\/2.bp.blogspot.com\/-qScJR8EKJjs\/UR4jHUJkiKI\/AAAAAAAAE3Y\/2xHYByzRZos\/s400\/polygraph2.jpeg\" width=\"400\" \/><\/a><\/div><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\">.<\/span><\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\">Imagina que hubiera una m\u00c3\u00a1quina capaz de detectar, para cada proposici\u00c3\u00b3n que escribamos en ella, si la proposici\u00c3\u00b3n es verdadera o falsa. Esa m\u00c3\u00a1quina, adem\u00c3\u00a1s, puede proporcionarnos cosas muy valiosas para nosotros (p.ej., la cura de una grave enfermedad de un familiar nuestro). La \u00c3\u00banica condici\u00c3\u00b3n para que la m\u00c3\u00a1quina nos suministre la medicina que curar\u00c3\u00a1 con seguridad a nuestro familiar es que&nbsp;<\/span><b style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\">escribamos con su teclado una frase verdadera<\/b><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\">. Yo no s\u00c3\u00a9 t\u00c3\u00ba, pero en mi caso, habr\u00c3\u00ada millones y millones de frases que, en esa circunstancia, yo escribir\u00c3\u00ada en el teclado antes de tener que poner <i>\u00e2\u20ac\u0153el universo tiene un fundamento \u00c3\u00baltimo que le da sentido moral a la existencia y que adem\u00c3\u00a1s es de naturaleza personal\u00e2\u20ac\u009d<\/i>; vamos, que no me jugar\u00c3\u00ada la salud de mis hijos (pongamos) si su salud tuviera que depender exclusivamente de que esa frase fuese verdadera o falsa, pudiendo hacerla depender de otras cosas.<\/span><\/span><br \/>.<br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\">Imag\u00c3\u00adnate tambi\u00c3\u00a9n que la m\u00c3\u00a1quina no te deja poner la frase que quieras, sino que cada vez te da dos frases distintas a elegir; de algunas estar\u00c3\u00a1s m\u00c3\u00a1s seguro que de otras, pero lo racional ser\u00c3\u00a1 elegir siempre aquella de la que est\u00c3\u00a1s m\u00c3\u00a1s seguro que es verdad. Podemos plantearnos entonces hacer una ordenaci\u00c3\u00b3n de todas las proposiciones seg\u00c3\u00ban lo m\u00c3\u00a1s o menos seguros que estemos de si son verdaderas. En mi caso particular, la frase \"existe un fundamento \u00c3\u00baltimo del universo, que tiene naturaleza personal, que es omnisciente y omnipotente, y que le da un sentido moral a la historia y a nuestras vidas\", no ser\u00c3\u00ada de las que estar\u00c3\u00adan m\u00c3\u00a1s arriba en esa ordenaci\u00c3\u00b3n seg\u00c3\u00ban la mayor o menor certeza. Es m\u00c3\u00a1s, para m\u00c3\u00ad, personalmente, tiene una probabilidad muy baja. Pero cada quien puede plantearse en su fuero interno qu\u00c3\u00a9 proposiciones considera M\u00c3\u0081S seguras que esa frase, cu\u00c3\u00a1les IGUAL de seguras, y cu\u00c3\u00a1les MENOS seguras. <span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\">.<\/span><\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\">.<\/span><\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif; font-size: large;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\"><b>Sigue a bordo:<\/b><\/span><\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\">.<\/span><\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\"><a href=\"http:\/\/abordodelottoneurath.blogspot.com.es\/search\/label\/argumentos%20ateol%C3%B3gicos\" >Argumentos ateol\u00c3\u00b3gicos<\/a><\/span><\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\"><a href=\"http:\/\/abordodelottoneurath.blogspot.com.es\/2009\/04\/creen-en-dios-los-creyentes-reposicion.html\" >\u00c2\u00bfCreen en dios los creyentes?<\/a><\/span><\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\"><a href=\"http:\/\/abordodelottoneurath.blogspot.com.es\/2010\/11\/por-la-desintoxicacion-de-los.html\" >Lecciones para vivir como si dios no existiera<\/a><\/span><\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\"><a href=\"http:\/\/abordodelottoneurath.blogspot.com.es\/2010\/09\/el-reto-de-dios.html\" >El reto de dios<\/a><\/span><\/span><br \/><span style=\"font-family: Arial, Helvetica, sans-serif;\"><span style=\"background-color: #f9f9f9; color: #666666; line-height: 19.799999237060547px;\"><br \/><\/span><\/span><div class=\"blogger-post-footer\">Enr\u00c3\u00b3late en el <i>Otto Neurath<\/i><\/div>","protected":false},"excerpt":{"rendered":"<p><span><span>(Contin&uacute;a la conversaci&oacute;n en <a href=\"http:\/\/opusprima.com\/2013\/02\/11\/es-posible-una-sociedad-cristiana-el-cristiano-no-es-perfecto-pero-el-cristianismo-si\/#comment-15866\" target=\"_blank\">Opus Prima<\/a>).<\/span><\/span><br \/><span><span><br \/><\/span><\/span><\/p>\n<div><a href=\"http:\/\/2.bp.blogspot.com\/-qScJR8EKJjs\/UR4jHUJkiKI\/AAAAAAAAE3Y\/2xHYByzRZos\/s1600\/polygraph2.jpeg\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"282\" src=\"http:\/\/2.bp.blogspot.com\/-qScJR8EKJjs\/UR4jHUJkiKI\/AAAAAAAAE3Y\/2xHYByzRZos\/s400\/polygraph2.jpeg\" width=\"400\"><\/a><\/div>\n<p><span><span>.<\/span><\/span><br \/><span><span>Imagina que hubiera una m&aacute;quina capaz de detectar, para cada proposici&oacute;n que escribamos en ella, si la proposici&oacute;n es verdadera o falsa. Esa m&aacute;quina, adem&aacute;s, puede proporcionarnos cosas muy valiosas para nosotros (p.ej., la cura de una grave enfermedad de un familiar nuestro). La &uacute;nica condici&oacute;n para que la m&aacute;quina nos suministre la medicina que curar&aacute; con seguridad a nuestro familiar es que&nbsp;<\/span><b>escribamos con su teclado una frase verdadera<\/b><span>. Yo no s&eacute; t&uacute;, pero en mi caso, habr&iacute;a millones y millones de frases que, en esa circunstancia, yo escribir&iacute;a en el teclado antes de tener que poner <i>&ldquo;el universo tiene un fundamento &uacute;ltimo que le da sentido moral a la existencia y que adem&aacute;s es de naturaleza personal&rdquo;<\/i>; vamos, que no me jugar&iacute;a la salud de mis hijos (pongamos) si su salud tuviera que depender exclusivamente de que esa frase fuese verdadera o falsa, pudiendo hacerla depender de otras cosas.<\/span><\/span><br \/>.<br \/><span>Imag&iacute;nate tambi&eacute;n que la m&aacute;quina no te deja poner la frase que quieras, sino que cada vez te da dos frases distintas a elegir; de algunas estar&aacute;s m&aacute;s seguro que de otras, pero lo racional ser&aacute; elegir siempre aquella de la que est&aacute;s m&aacute;s seguro que es verdad. Podemos plantearnos entonces hacer una ordenaci&oacute;n de todas las proposiciones seg&uacute;n lo m&aacute;s o menos seguros que estemos de si son verdaderas. En mi caso particular, la frase &#8220;existe un fundamento &uacute;ltimo del universo, que tiene naturaleza personal, que es omnisciente y omnipotente, y que le da un sentido moral a la historia y a nuestras vidas&#8221;, no ser&iacute;a de las que estar&iacute;an m&aacute;s arriba en esa ordenaci&oacute;n seg&uacute;n la mayor o menor certeza. Es m&aacute;s, para m&iacute;, personalmente, tiene una probabilidad muy baja. Pero cada quien puede plantearse en su fuero interno qu&eacute; proposiciones considera M&Aacute;S seguras que esa frase, cu&aacute;les IGUAL de seguras, y cu&aacute;les MENOS seguras. <span>.<\/span><\/span><br \/><span><span>.<\/span><\/span><br \/><span><span><b>Sigue a bordo:<\/b><\/span><\/span><br \/><span><span>.<\/span><\/span><br \/><span><span><a href=\"http:\/\/abordodelottoneurath.blogspot.com.es\/search\/label\/argumentos%20ateol%C3%B3gicos\" target=\"_blank\">Argumentos ateol&oacute;gicos<\/a><\/span><\/span><br \/><span><span><a href=\"http:\/\/abordodelottoneurath.blogspot.com.es\/2009\/04\/creen-en-dios-los-creyentes-reposicion.html\" target=\"_blank\">&iquest;Creen en dios los creyentes?<\/a><\/span><\/span><br \/><span><span><a href=\"http:\/\/abordodelottoneurath.blogspot.com.es\/2010\/11\/por-la-desintoxicacion-de-los.html\" target=\"_blank\">Lecciones para vivir como si dios no existiera<\/a><\/span><\/span><br \/><span><span><a href=\"http:\/\/abordodelottoneurath.blogspot.com.es\/2010\/09\/el-reto-de-dios.html\" target=\"_blank\">El reto de dios<\/a><\/span><\/span><br \/><span><span><br \/><\/span><\/span><\/p>\n<div>Enr&oacute;late en el <i>Otto Neurath<\/i>\n<\/div>\n","protected":false},"author":184,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[426,4,23],"tags":[],"class_list":["post-20418","post","type-post","status-publish","format-standard","hentry","category-argumentos-ateologicos","category-blogs-colaboradores","category-religion"],"_links":{"self":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts\/20418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/users\/184"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/comments?post=20418"}],"version-history":[{"count":0,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts\/20418\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/media?parent=20418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/categories?post=20418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/tags?post=20418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}