{"id":22814,"date":"2014-03-26T01:52:00","date_gmt":"2014-03-26T00:52:00","guid":{"rendered":"http:\/\/redatea.net\/?guid=380d4806027d311ea8d2ad206b842303"},"modified":"2014-03-26T01:52:00","modified_gmt":"2014-03-26T00:52:00","slug":"la-religion-hace-que-aceptes-lo-absurdo-como-algo-normal","status":"publish","type":"post","link":"http:\/\/piensa-luegoexiste.blogspot.com\/2014\/03\/la-religion-hace-que-aceptes-lo-absurdo.html","title":{"rendered":"La religi\u00c3\u00b3n hace que aceptes lo absurdo como algo normal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>En varias oportunidades, en este blog, he demostrado como la religi\u00c3\u00b3n hace que personas normales en otros aspectos, act\u00c3\u00baen de forma absurda cuando a religi\u00c3\u00b3n se refiere.<\/p>\n<p>Desde situaciones c\u00c3\u00b3micas como estas dos entradas ac\u00c3\u00a1 y ac\u00c3\u00a1, hasta justificar la muerte con ello.<\/p>\n<p>Hoy, pues solo algo para reflexionar, esta imagen de un ni\u00c3\u00b1o&#8230; \u00c2\u00bfhasta d\u00c3\u00b3nde entender\u00c3\u00a1 lo absurdo de la creencia de sus padres?<\/p>\n","protected":false},"author":189,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,356,115,62],"tags":[],"class_list":["post-22814","post","type-post","status-publish","format-standard","hentry","category-blogs-colaboradores","category-creencias","category-fanatismo","category-iglesia-catolica"],"_links":{"self":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts\/22814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/users\/189"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/comments?post=22814"}],"version-history":[{"count":0,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts\/22814\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/media?parent=22814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/categories?post=22814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/tags?post=22814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}