{"id":23593,"date":"2014-10-23T21:05:00","date_gmt":"2014-10-23T20:05:00","guid":{"rendered":"http:\/\/redatea.net\/?guid=616f218b2f73954fc0c2b80a719aa177"},"modified":"2014-10-23T21:05:00","modified_gmt":"2014-10-23T20:05:00","slug":"el-cancer-desde-la-cosmologia","status":"publish","type":"post","link":"http:\/\/blog-sin-dioses.blogspot.com\/2014\/10\/el-cancer-desde-la-cosmologia.html","title":{"rendered":"El c\u00c3\u00a1ncer desde la cosmolog\u00c3\u00ada"},"content":{"rendered":"\u00c2\u00bfPodr\u00c3\u00ada un cosm\u00c3\u00b3logo encontrar la cura contra el c\u00c3\u00a1ncer? Hace siete a\u00c3\u00b1os, la Universidad del Estado de Arizona decidi\u00c3\u00b3 incurrir en esta grave enfermedad desde distintos \u00c3\u00a1ngulos. Aqu\u00c3\u00ad sus primeras propuestas.<br \/><br \/><div class=\"separator\" style=\"clear: both; text-align: center;\"><a href=\"http:\/\/3.bp.blogspot.com\/-fmpGnbj8rus\/VElfH55fRHI\/AAAAAAAAg4Y\/KsiG14CUpd8\/s1600\/cancer.jpg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img border=\"0\" src=\"http:\/\/3.bp.blogspot.com\/-fmpGnbj8rus\/VElfH55fRHI\/AAAAAAAAg4Y\/KsiG14CUpd8\/s1600\/cancer.jpg\" height=\"400\" width=\"640\" \/><\/a><\/div><br \/><br \/>Por Glenys \u00c3\u0081lvarez<br \/><br \/>Hace algunos a\u00c3\u00b1os, en un laboratorio de investigaci\u00c3\u00b3n oncol\u00c3\u00b3gica en San Diego, California, uno de los cient\u00c3\u00adficos, colombiano por cierto, me dijo que nunca hab\u00c3\u00ada visto algo tan complejo como las c\u00c3\u00a9lulas cancerosas bajo el microscopio. No tengo idea sobre la complejidad biol\u00c3\u00b3gica del c\u00c3\u00a1ncer pero s\u00c3\u00ad puedo creer esa afirmaci\u00c3\u00b3n debido a lo dificultoso que ha sido entender la enfermedad y tratarla. De hecho, hace siete a\u00c3\u00b1os, la Universidad del Estado de Arizona inici\u00c3\u00b3 un programa bastante curioso. La idea era tratar al c\u00c3\u00a1ncer por todos los \u00c3\u00a1ngulos posibles, no s\u00c3\u00b3lo el biol\u00c3\u00b3gico, reunir investigadores en la f\u00c3\u00adsica, la evoluci\u00c3\u00b3n y la cosmolog\u00c3\u00ada para comenzar a trazarle un camino a estas c\u00c3\u00a9lulas, entenderlas mejor, saber su origen y para qu\u00c3\u00a9 surgieron. El fin es, por supuesto, erradicar el c\u00c3\u00a1ncer de nuestra lista de problemas m\u00c3\u00a9dicos.<br \/><br \/>Pues bien, a principios de este mes, una curiosa noticia sobre las c\u00c3\u00a9lulas cancerosas aseguraba que el c\u00c3\u00a1ncer es una nueva expresi\u00c3\u00b3n de un rasgo antiguo que estaba preprogramado en las c\u00c3\u00a9lulas pero que hab\u00c3\u00ada permanecido inactivo... hasta ahora.<br \/><br \/>Los investigadores involucrados en los nuevos resultados son Paul Davies, cosm\u00c3\u00b3logo, astrobi\u00c3\u00b3logo, f\u00c3\u00adsico te\u00c3\u00b3rico cuyas investigaciones han ayudado a explicar c\u00c3\u00b3mo los agujeros negros irradian energ\u00c3\u00ada, qu\u00c3\u00a9 caus\u00c3\u00b3 las ondas en el resplandor c\u00c3\u00b3smico de la gran explosi\u00c3\u00b3n y por qu\u00c3\u00a9 la vida en la Tierra pudo haber venido de Marte; Charley Lineweaver, astrobi\u00c3\u00b3logo de la Universidad Nacional Australiana en Canberra, y Mark Vincent, onc\u00c3\u00b3logo en el Centro de las Ciencias de la Salud en Ontario; juntos argumentan en un nuevo art\u00c3\u00adculo publicado en BioEssays, que como el c\u00c3\u00a1ncer aparece en muchos animales y plantas, as\u00c3\u00ad como en los seres humanos, es posible entonces que haya evolucionado cientos de millones de a\u00c3\u00b1os atr\u00c3\u00a1s, cuando compartimos un ancestro unicelular com\u00c3\u00ban.<br \/><br \/>Sabemos que el problema de estas c\u00c3\u00a9lulas es que no mueren, son inmortales. Para ellas, la apoptosis carece de significado y contin\u00c3\u00baan prolifer\u00c3\u00a1ndose sin que nada las controle. Los investigadores argumentan que esta caracter\u00c3\u00adstica pudo haber sido necesaria una vez, en aquellos d\u00c3\u00adas cuando los organismos multicelulares complejos se desarrollaron.<br \/><br \/>\u00e2\u20ac\u0153Cuando esto ocurri\u00c3\u00b3, la inmortalidad fue externalizada hacia los \u00c3\u00b3vulos y los espermatozoides y las c\u00c3\u00a9lulas som\u00c3\u00a1ticas, aquellas que no participan en la reproducci\u00c3\u00b3n, ya no se necesitaban para esta funci\u00c3\u00b3n\u00e2\u20ac\u009d, explic\u00c3\u00b3 Davies durante una conferencia de ingenier\u00c3\u00ada m\u00c3\u00a9dica celebrada en el Imperial College de Londres el pasado mes de septiembre.<br \/><br \/>Esto es lo que nos dice el equipo de acuerdo con un editorial en el diario Nature escrito por Zeeya Merali: Cuando una c\u00c3\u00a9lula se enfrenta a una amenaza ambiental, la radiaci\u00c3\u00b3n, por ejemplo, o un factor de estilo de vida, puede regresar a un 'modo seguro preprogramado'. &nbsp;As\u00c3\u00ad, en un intento equivocado para sobrevivir, las c\u00c3\u00a9lulas se deshacen de su alta funcionalidad cambi\u00c3\u00a1ndolas por su capacidad latente de proliferar de nuevo.<br \/><br \/>La enfermedad, indican, es una caja fuerte contra fallos, pero es antigua y una vez se activa, \u00e2\u20ac\u0153implementa su programa sin piedad\u00e2\u20ac\u009d, dijo Davies.<br \/><br \/>Otra de las aseveraciones del estudio es que el c\u00c3\u00a1ncer se desarroll\u00c3\u00b3 en un momento cuando el medio ambiente terrestre era m\u00c3\u00a1s \u00c3\u00a1cido y conten\u00c3\u00ada menos ox\u00c3\u00adgeno. Por eso recomiendan tratamientos con altos niveles de ox\u00c3\u00adgeno y poca az\u00c3\u00bacar en la dieta para disminuir la acidez, eso tensar\u00c3\u00a1 el c\u00c3\u00a1ncer reduciendo el tama\u00c3\u00b1o de los tumores.<br \/><br \/>Nada nuevo bajo el sol<br \/>El problema es que ambas recomendaciones de tratamientos ya hab\u00c3\u00adan sido hechas antes. Estudios independientes llegaron a conclusiones parecidas sobre el uso del ox\u00c3\u00adgeno, sin embargo, los resultados a\u00c3\u00ban no han sido publicados. Constantino Balestra y equipo, de la Universidad de Bruselas, experimentaron con ox\u00c3\u00adgeno reduciendo las c\u00c3\u00a9lulas de c\u00c3\u00a1ncer en la leucemia pero sus resultados est\u00c3\u00a1n siendo revisados. Indudablemente, la idea de aplicar ox\u00c3\u00adgeno parece muy simple. M\u00c3\u00a1s a\u00c3\u00ban cuando se prescribe junto a los tratamientos ya conocidos, es algo as\u00c3\u00ad como la p\u00c3\u00adldora para adelgazar que s\u00c3\u00b3lo funciona si hacemos ejercicio y llevamos una dieta estricta; ya veremos que ocurre despu\u00c3\u00a9s de la revisi\u00c3\u00b3n.<br \/><br \/>Por otro lado, el equipo de Davies tambi\u00c3\u00a9n propone \u00e2\u20ac\u0153terapias inmunol\u00c3\u00b3gicas\u00e2\u20ac\u009d. La idea es despertar nuestras defensas para que ellas mismas se encarguen de devorar el c\u00c3\u00a1ncer. Otro m\u00c3\u00a9todo que tambi\u00c3\u00a9n se ha estudiado antes y que se centra en infectar a los pacientes de forma selectiva con bacterias y agentes virales para dinamizar el sistema de defensa. De hecho, algunos melanomas han reaccionado positivamente ante esta estrategia y se estima que las c\u00c3\u00a9lulas cancer\u00c3\u00adgenas no s\u00c3\u00b3lo ser\u00c3\u00adan m\u00c3\u00a1s vulnerables as\u00c3\u00ad a nuestro sistema de defensa sino a los agentes infecciosos tambi\u00c3\u00a9n, que las aniquilar\u00c3\u00adan con mayor facilidad que a nuestras c\u00c3\u00a9lulas saludables. Lo cual es una buena noticia.<br \/><br \/>Pero igualmente, no todos est\u00c3\u00a1n de acuerdo debido a que las \u00e2\u20ac\u0153predicciones de atavismo\u00e2\u20ac\u009d, como expres\u00c3\u00b3 David Gorski, cirujano onc\u00c3\u00b3logo de la Universidad Estatal de Wayne en Detroit, Michigan, no son nuevas en la oncolog\u00c3\u00ada, ya que los cient\u00c3\u00adficos han llegado a ellas \u00e2\u20ac\u0153por otros caminos\".<br \/><br \/>Es indudable que el c\u00c3\u00a1ncer contin\u00c3\u00baa ganando la guerra m\u00c3\u00a9dica en el planeta y todav\u00c3\u00ada no sabemos c\u00c3\u00b3mo se encontrar\u00c3\u00a1 la cura para tan compleja enfermedad.<br \/><br \/>\u00e2\u20ac\u0153Enormes cantidades de dinero y las mentes m\u00c3\u00a1s brillantes de la ciencia biol\u00c3\u00b3gica y m\u00c3\u00a9dica no han logrado hacer un gran impacto en la guerra contra el c\u00c3\u00a1ncer, a lo mejor es hora de un nuevo paradigma. Un cosm\u00c3\u00b3logo puede observar las c\u00c3\u00a9lulas como un 'universo interno' y explorarlo de una &nbsp;forma novedosa\u00e2\u20ac\u009d, expres\u00c3\u00b3 para Nature, Brendon Coventry, onc\u00c3\u00b3logo quir\u00c3\u00bargico e immunoterapista en la Universidad de Adelaida, en Australia.","protected":false},"excerpt":{"rendered":"<p>&iquest;Podr&iacute;a un cosm&oacute;logo encontrar la cura contra el c&aacute;ncer? Hace siete a&ntilde;os, la Universidad del Estado de Arizona decidi&oacute; incurrir en esta grave enfermedad desde distintos &aacute;ngulos. Aqu&iacute; sus primeras propuestas.<\/p>\n<div><a href=\"http:\/\/3.bp.blogspot.com\/-fmpGnbj8rus\/VElfH55fRHI\/AAAAAAAAg4Y\/KsiG14CUpd8\/s1600\/cancer.jpg\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"http:\/\/3.bp.blogspot.com\/-fmpGnbj8rus\/VElfH55fRHI\/AAAAAAAAg4Y\/KsiG14CUpd8\/s1600\/cancer.jpg\" height=\"400\" width=\"640\"><\/a><\/div>\n<p>Por Glenys &Aacute;lvarez<\/p>\n<p>Hace algunos a&ntilde;os, en un laboratorio de investigaci&oacute;n oncol&oacute;gica en San Diego, California, uno de los cient&iacute;ficos, colombiano por cierto, me dijo que nunca hab&iacute;a visto algo tan complejo como las c&eacute;lulas cancerosas bajo el microscopio. No tengo idea sobre la complejidad biol&oacute;gica del c&aacute;ncer pero s&iacute; puedo creer esa afirmaci&oacute;n debido a lo dificultoso que ha sido entender la enfermedad y tratarla. De hecho, hace siete a&ntilde;os, la Universidad del Estado de Arizona inici&oacute; un programa bastante curioso. La idea era tratar al c&aacute;ncer por todos los &aacute;ngulos posibles, no s&oacute;lo el biol&oacute;gico, reunir investigadores en la f&iacute;sica, la evoluci&oacute;n y la cosmolog&iacute;a para comenzar a trazarle un camino a estas c&eacute;lulas, entenderlas mejor, saber su origen y para qu&eacute; surgieron. El fin es, por supuesto, erradicar el c&aacute;ncer de nuestra lista de problemas m&eacute;dicos.<\/p>\n<p>Pues bien, a principios de este mes, una curiosa noticia sobre las c&eacute;lulas cancerosas aseguraba que el c&aacute;ncer es una nueva expresi&oacute;n de un rasgo antiguo que estaba preprogramado en las c&eacute;lulas pero que hab&iacute;a permanecido inactivo&#8230; hasta ahora.<\/p>\n<p>Los investigadores involucrados en los nuevos resultados son Paul Davies, cosm&oacute;logo, astrobi&oacute;logo, f&iacute;sico te&oacute;rico cuyas investigaciones han ayudado a explicar c&oacute;mo los agujeros negros irradian energ&iacute;a, qu&eacute; caus&oacute; las ondas en el resplandor c&oacute;smico de la gran explosi&oacute;n y por qu&eacute; la vida en la Tierra pudo haber venido de Marte; Charley Lineweaver, astrobi&oacute;logo de la Universidad Nacional Australiana en Canberra, y Mark Vincent, onc&oacute;logo en el Centro de las Ciencias de la Salud en Ontario; juntos argumentan en un nuevo art&iacute;culo publicado en BioEssays, que como el c&aacute;ncer aparece en muchos animales y plantas, as&iacute; como en los seres humanos, es posible entonces que haya evolucionado cientos de millones de a&ntilde;os atr&aacute;s, cuando compartimos un ancestro unicelular com&uacute;n.<\/p>\n<p>Sabemos que el problema de estas c&eacute;lulas es que no mueren, son inmortales. Para ellas, la apoptosis carece de significado y contin&uacute;an prolifer&aacute;ndose sin que nada las controle. Los investigadores argumentan que esta caracter&iacute;stica pudo haber sido necesaria una vez, en aquellos d&iacute;as cuando los organismos multicelulares complejos se desarrollaron.<\/p>\n<p>&ldquo;Cuando esto ocurri&oacute;, la inmortalidad fue externalizada hacia los &oacute;vulos y los espermatozoides y las c&eacute;lulas som&aacute;ticas, aquellas que no participan en la reproducci&oacute;n, ya no se necesitaban para esta funci&oacute;n&rdquo;, explic&oacute; Davies durante una conferencia de ingenier&iacute;a m&eacute;dica celebrada en el Imperial College de Londres el pasado mes de septiembre.<\/p>\n<p>Esto es lo que nos dice el equipo de acuerdo con un editorial en el diario Nature escrito por Zeeya Merali: Cuando una c&eacute;lula se enfrenta a una amenaza ambiental, la radiaci&oacute;n, por ejemplo, o un factor de estilo de vida, puede regresar a un &#8216;modo seguro preprogramado&#8217;. &nbsp;As&iacute;, en un intento equivocado para sobrevivir, las c&eacute;lulas se deshacen de su alta funcionalidad cambi&aacute;ndolas por su capacidad latente de proliferar de nuevo.<\/p>\n<p>La enfermedad, indican, es una caja fuerte contra fallos, pero es antigua y una vez se activa, &ldquo;implementa su programa sin piedad&rdquo;, dijo Davies.<\/p>\n<p>Otra de las aseveraciones del estudio es que el c&aacute;ncer se desarroll&oacute; en un momento cuando el medio ambiente terrestre era m&aacute;s &aacute;cido y conten&iacute;a menos ox&iacute;geno. Por eso recomiendan tratamientos con altos niveles de ox&iacute;geno y poca az&uacute;car en la dieta para disminuir la acidez, eso tensar&aacute; el c&aacute;ncer reduciendo el tama&ntilde;o de los tumores.<\/p>\n<p>Nada nuevo bajo el sol<br \/>El problema es que ambas recomendaciones de tratamientos ya hab&iacute;an sido hechas antes. Estudios independientes llegaron a conclusiones parecidas sobre el uso del ox&iacute;geno, sin embargo, los resultados a&uacute;n no han sido publicados. Constantino Balestra y equipo, de la Universidad de Bruselas, experimentaron con ox&iacute;geno reduciendo las c&eacute;lulas de c&aacute;ncer en la leucemia pero sus resultados est&aacute;n siendo revisados. Indudablemente, la idea de aplicar ox&iacute;geno parece muy simple. M&aacute;s a&uacute;n cuando se prescribe junto a los tratamientos ya conocidos, es algo as&iacute; como la p&iacute;ldora para adelgazar que s&oacute;lo funciona si hacemos ejercicio y llevamos una dieta estricta; ya veremos que ocurre despu&eacute;s de la revisi&oacute;n.<\/p>\n<p>Por otro lado, el equipo de Davies tambi&eacute;n propone &ldquo;terapias inmunol&oacute;gicas&rdquo;. La idea es despertar nuestras defensas para que ellas mismas se encarguen de devorar el c&aacute;ncer. Otro m&eacute;todo que tambi&eacute;n se ha estudiado antes y que se centra en infectar a los pacientes de forma selectiva con bacterias y agentes virales para dinamizar el sistema de defensa. De hecho, algunos melanomas han reaccionado positivamente ante esta estrategia y se estima que las c&eacute;lulas cancer&iacute;genas no s&oacute;lo ser&iacute;an m&aacute;s vulnerables as&iacute; a nuestro sistema de defensa sino a los agentes infecciosos tambi&eacute;n, que las aniquilar&iacute;an con mayor facilidad que a nuestras c&eacute;lulas saludables. Lo cual es una buena noticia.<\/p>\n<p>Pero igualmente, no todos est&aacute;n de acuerdo debido a que las &ldquo;predicciones de atavismo&rdquo;, como expres&oacute; David Gorski, cirujano onc&oacute;logo de la Universidad Estatal de Wayne en Detroit, Michigan, no son nuevas en la oncolog&iacute;a, ya que los cient&iacute;ficos han llegado a ellas &ldquo;por otros caminos&#8221;.<\/p>\n<p>Es indudable que el c&aacute;ncer contin&uacute;a ganando la guerra m&eacute;dica en el planeta y todav&iacute;a no sabemos c&oacute;mo se encontrar&aacute; la cura para tan compleja enfermedad.<\/p>\n<p>&ldquo;Enormes cantidades de dinero y las mentes m&aacute;s brillantes de la ciencia biol&oacute;gica y m&eacute;dica no han logrado hacer un gran impacto en la guerra contra el c&aacute;ncer, a lo mejor es hora de un nuevo paradigma. Un cosm&oacute;logo puede observar las c&eacute;lulas como un &#8216;universo interno&#8217; y explorarlo de una &nbsp;forma novedosa&rdquo;, expres&oacute; para Nature, Brendon Coventry, onc&oacute;logo quir&uacute;rgico e immunoterapista en la Universidad de Adelaida, en Australia.<\/p>\n","protected":false},"author":190,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1352,4,1345,1066,532,1346,1347,881,1349,1350,1348,1351,739],"tags":[],"class_list":["post-23593","post","type-post","status-publish","format-standard","hentry","category-ovulos","category-blogs-colaboradores","category-cacerosos","category-cancer","category-cosmologia","category-doctor","category-enfermedad","category-genetica","category-medica","category-medico","category-multicelular","category-oncologia","category-salud"],"_links":{"self":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts\/23593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/users\/190"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/comments?post=23593"}],"version-history":[{"count":0,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts\/23593\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/media?parent=23593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/categories?post=23593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/tags?post=23593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}