{"id":54721,"date":"2020-04-17T21:26:00","date_gmt":"2020-04-17T20:26:00","guid":{"rendered":"http:\/\/redatea.net\/?guid=a27cc957938a61e8333b17818e57a373"},"modified":"2020-04-17T21:26:00","modified_gmt":"2020-04-17T20:26:00","slug":"la-terrible-logica-religiosa-sobre-el-coronavirus","status":"publish","type":"post","link":"http:\/\/blog-sin-dioses.blogspot.com\/2020\/04\/la-terrible-logica-religiosa-sobre-el.html","title":{"rendered":"La terrible l\u00c3\u00b3gica religiosa sobre el coronavirus"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\"><a href=\"https:\/\/1.bp.blogspot.com\/-UURRNVjaN54\/XpoQxM4nOAI\/AAAAAAAAUeI\/sxVG1Kg_QY07kEnfmYazGkPafwpRzsHdACLcBGAsYHQ\/s1600\/por%2Bqu%25C3%25A9%2Bdios%2Bpermite%2Bla%2Bpandemia.jpg\" imageanchor=\"1\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img border=\"0\" data-original-height=\"405\" data-original-width=\"725\" height=\"222\" src=\"https:\/\/1.bp.blogspot.com\/-UURRNVjaN54\/XpoQxM4nOAI\/AAAAAAAAUeI\/sxVG1Kg_QY07kEnfmYazGkPafwpRzsHdACLcBGAsYHQ\/s400\/por%2Bqu%25C3%25A9%2Bdios%2Bpermite%2Bla%2Bpandemia.jpg\" width=\"400\" \/><\/a><\/div>La pandemia de covid-19 ha ocupado casi todo el espacio noticioso y las pr\u00c3\u00a9dicas de los cl\u00c3\u00a9rigos no han escapado a esto. Sin embargo, explicar porqu\u00c3\u00a9 su Dios, presuntamente amoroso permite tal tragedia, ha sido tarea reciente para muchos de ellos.<br \/><br \/>Las explicaciones religiosas no han sido un\u00c3\u00a1nimes, y mayoritariamente caben en estos tres tipos:<br \/><br \/><br \/>1) Castigo de Dios o resultado de la ira de Dios.<br \/>2) Es se\u00c3\u00b1al del fin del mundo o segundo advenimiento<br \/>3) Es una manera como Dios nos llama al arrepentimiento.<br \/><br \/>Todas ellas son absurdas e il\u00c3\u00b3gicas. Un an\u00c3\u00a1lisis de estas respuestas es lo que tratamos en este programa de Bogot\u00c3\u00a1 Atea que compartimos a continuaci\u00c3\u00b3n<br \/><br \/><iframe allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/0VTrkmwqfcU\" width=\"560\"><\/iframe>","protected":false},"excerpt":{"rendered":"<div><a href=\"https:\/\/1.bp.blogspot.com\/-UURRNVjaN54\/XpoQxM4nOAI\/AAAAAAAAUeI\/sxVG1Kg_QY07kEnfmYazGkPafwpRzsHdACLcBGAsYHQ\/s1600\/por%2Bqu%25C3%25A9%2Bdios%2Bpermite%2Bla%2Bpandemia.jpg\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"222\" src=\"https:\/\/1.bp.blogspot.com\/-UURRNVjaN54\/XpoQxM4nOAI\/AAAAAAAAUeI\/sxVG1Kg_QY07kEnfmYazGkPafwpRzsHdACLcBGAsYHQ\/s400\/por%2Bqu%25C3%25A9%2Bdios%2Bpermite%2Bla%2Bpandemia.jpg\" width=\"400\"><\/a><\/div>\n<p>La pandemia de covid-19 ha ocupado casi todo el espacio noticioso y las pr&eacute;dicas de los cl&eacute;rigos no han escapado a esto. Sin embargo, explicar porqu&eacute; su Dios, presuntamente amoroso permite tal tragedia, ha sido tarea reciente para muchos de ellos.<\/p>\n<p>Las explicaciones religiosas no han sido un&aacute;nimes, y mayoritariamente caben en estos tres tipos:<\/p>\n<p>1) Castigo de Dios o resultado de la ira de Dios.<br \/>2) Es se&ntilde;al del fin del mundo o segundo advenimiento<br \/>3) Es una manera como Dios nos llama al arrepentimiento.<\/p>\n<p>Todas ellas son absurdas e il&oacute;gicas. Un an&aacute;lisis de estas respuestas es lo que tratamos en este programa de Bogot&aacute; Atea que compartimos a continuaci&oacute;n<\/p>\n","protected":false},"author":170,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1833,108,1874,483],"tags":[],"class_list":["post-54721","post","type-post","status-publish","format-standard","hentry","category-blogs-colaboradores","category-coronavirus","category-cristianismo","category-ira-de-dios","category-segunda-venida-de-jesus"],"_links":{"self":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts\/54721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/users\/170"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/comments?post=54721"}],"version-history":[{"count":0,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/posts\/54721\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/media?parent=54721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/categories?post=54721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redatea.net\/index.php\/wp-json\/wp\/v2\/tags?post=54721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}